{"id":1917,"date":"2021-11-02T10:21:09","date_gmt":"2021-11-02T10:21:09","guid":{"rendered":"https:\/\/bermeon-berton.com\/?p=1917"},"modified":"2021-11-02T11:11:51","modified_gmt":"2021-11-02T11:11:51","slug":"bermeo-txartela-consigue-la-tuya","status":"publish","type":"post","link":"https:\/\/bermeon-berton.com\/es\/bermeo-txartela-consigue-la-tuya\/","title":{"rendered":"BERMEO TXARTELA. CONSIGUE LA TUYA!"},"content":{"rendered":"\n<p><strong>TODO EL A\u00d1O<\/strong> <strong><u>DTO PARA LA SIGUIENTE COMPRA EN EL MISMO COMERCIO<\/u><\/strong><\/p>\n\n\n\n<p>Desde el 1 de enero al 31 de diciembre de 2.021. Descuento en la siguiente compra de hasta \u00a010<strong>% <\/strong>en las compras realizadas con la Bermeo Txartela en los comercios asociados<strong> y adheridos a esta campa\u00f1a de fidelizaci\u00f3n.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"975\" height=\"1024\" src=\"https:\/\/bermeon-berton.com\/wp-content\/uploads\/2021\/11\/Diptico-interior-975x1024.jpg\" alt=\"\" class=\"wp-image-1918\" srcset=\"https:\/\/bermeon-berton.com\/wp-content\/uploads\/2021\/11\/Diptico-interior-975x1024.jpg 975w, https:\/\/bermeon-berton.com\/wp-content\/uploads\/2021\/11\/Diptico-interior-286x300.jpg 286w, https:\/\/bermeon-berton.com\/wp-content\/uploads\/2021\/11\/Diptico-interior-768x806.jpg 768w, https:\/\/bermeon-berton.com\/wp-content\/uploads\/2021\/11\/Diptico-interior-1463x1536.jpg 1463w, https:\/\/bermeon-berton.com\/wp-content\/uploads\/2021\/11\/Diptico-interior-1951x2048.jpg 1951w\" sizes=\"(max-width: 975px) 100vw, 975px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>TODO EL A\u00d1O DTO PARA LA SIGUIENTE COMPRA EN EL MISMO COMERCIO Desde el 1 de enero al 31 de diciembre de 2.021. Descuento en la siguiente compra de hasta \u00a010% en las compras realizadas con la Bermeo Txartela en los comercios asociados y adheridos a esta campa\u00f1a de fidelizaci\u00f3n.<\/p>\n","protected":false},"author":3,"featured_media":1918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-1917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"_links":{"self":[{"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/posts\/1917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/comments?post=1917"}],"version-history":[{"count":3,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/posts\/1917\/revisions"}],"predecessor-version":[{"id":1977,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/posts\/1917\/revisions\/1977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/media\/1918"}],"wp:attachment":[{"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/media?parent=1917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/categories?post=1917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bermeon-berton.com\/es\/wp-json\/wp\/v2\/tags?post=1917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}